{"id":54626,"date":"2026-01-14T20:22:27","date_gmt":"2026-01-14T19:22:27","guid":{"rendered":"https:\/\/musica.santjosep.org\/concert\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/"},"modified":"2026-01-14T20:24:23","modified_gmt":"2026-01-14T19:24:23","slug":"elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2","status":"publish","type":"tribe_events","link":"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/","title":{"rendered":"Elio Crispo y su espect\u00e1culo de canciones en ingl\u00e9s \u2018I Love the 80\u2019s\u2019 en Cas Costas"},"content":{"rendered":"<p>Eleonora Crispo, <em>Elio<\/em>, una de las cantantes de tango m\u00e1s prestigiosas de Ibiza como parte del d\u00fao Mano a mano, act\u00faa esta vez en solitario en el escenario del restaurante Cas Costas, con el espect\u00e1culo \u2018I Love the 80\u2019s\u2019. Guitarra en mano, Elio trae versiones de canciones en ingl\u00e9s que triunfaron en aquella \u00e9poca dorada, popularizadas por grupos y artistas como The Cure, Wham, Toto, REM, Alphaville, Rod Stewart, Erasure, Tears for fears, Simple Red\u2026 Un espect\u00e1culo ac\u00fastico e \u00edntimo, aderezado tambi\u00e9n de improvisaciones y melod\u00edas propias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eleonora Crispo, Elio, una de las cantantes de tango m\u00e1s prestigiosas de Ibiza como parte del d\u00fao Mano a mano, act\u00faa esta vez en solitario en el escenario del restaurante Cas Costas, con el espect\u00e1culo \u2018I Love the 80\u2019s\u2019. Guitarra [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":53173,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[29,15],"class_list":["post-54626","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-pop","tribe_events_cat-rock","cat_pop","cat_rock"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elio Crispo y su espect\u00e1culo de canciones en ingl\u00e9s \u2018I Love the 80\u2019s\u2019 en Cas Costas - Sant Josep \u00e9s m\u00fasica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elio Crispo y su espect\u00e1culo de canciones en ingl\u00e9s \u2018I Love the 80\u2019s\u2019 en Cas Costas - Sant Josep \u00e9s m\u00fasica\" \/>\n<meta property=\"og:description\" content=\"Eleonora Crispo, Elio, una de las cantantes de tango m\u00e1s prestigiosas de Ibiza como parte del d\u00fao Mano a mano, act\u00faa esta vez en solitario en el escenario del restaurante Cas Costas, con el espect\u00e1culo \u2018I Love the 80\u2019s\u2019. Guitarra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Sant Josep \u00e9s m\u00fasica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-14T19:24:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2025\/10\/elio-2-rec.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicaSantJosep\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\\\/\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\\\/\",\"name\":\"Elio Crispo y su espect\u00e1culo de canciones en ingl\u00e9s \u2018I Love the 80\u2019s\u2019 en Cas Costas - Sant Josep \u00e9s m\u00fasica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/elio-2-rec.jpg\",\"datePublished\":\"2026-01-14T19:22:27+00:00\",\"dateModified\":\"2026-01-14T19:24:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/elio-2-rec.jpg\",\"contentUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/elio-2-rec.jpg\",\"width\":1400,\"height\":933},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concerts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Elio Crispo y su espect\u00e1culo de canciones en ingl\u00e9s \u2018I Love the 80\u2019s\u2019 en Cas Costas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\",\"name\":\"Sant Josep \u00e9s m\u00fasica\",\"description\":\"Informaci\u00f3n actualizada de todos los conciertos, grupos y artistas que act\u00faen tanto en fiestas y festivales, como en establecimientos privados en el municipio de Sant Josep de sa Talaia\",\"publisher\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#organization\",\"name\":\"Sant Josep \u00e9s m\u00fasica\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-SJEM.png\",\"contentUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-SJEM.png\",\"width\":213,\"height\":103,\"caption\":\"Sant Josep \u00e9s m\u00fasica\"},\"image\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sant-Josep-s-Msica-105337042007790\",\"https:\\\/\\\/x.com\\\/MusicaSantJosep\",\"https:\\\/\\\/www.instagram.com\\\/musicasantjosep\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBSLSUpqfrfsiOMVslmZEJA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elio Crispo y su espect\u00e1culo de canciones en ingl\u00e9s \u2018I Love the 80\u2019s\u2019 en Cas Costas - Sant Josep \u00e9s m\u00fasica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/","og_locale":"es_ES","og_type":"article","og_title":"Elio Crispo y su espect\u00e1culo de canciones en ingl\u00e9s \u2018I Love the 80\u2019s\u2019 en Cas Costas - Sant Josep \u00e9s m\u00fasica","og_description":"Eleonora Crispo, Elio, una de las cantantes de tango m\u00e1s prestigiosas de Ibiza como parte del d\u00fao Mano a mano, act\u00faa esta vez en solitario en el escenario del restaurante Cas Costas, con el espect\u00e1culo \u2018I Love the 80\u2019s\u2019. Guitarra [&hellip;]","og_url":"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/","og_site_name":"Sant Josep \u00e9s m\u00fasica","article_publisher":"https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790","article_modified_time":"2026-01-14T19:24:23+00:00","og_image":[{"width":1400,"height":933,"url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2025\/10\/elio-2-rec.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicaSantJosep","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/","url":"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/","name":"Elio Crispo y su espect\u00e1culo de canciones en ingl\u00e9s \u2018I Love the 80\u2019s\u2019 en Cas Costas - Sant Josep \u00e9s m\u00fasica","isPartOf":{"@id":"https:\/\/musica.santjosep.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/#primaryimage"},"image":{"@id":"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/#primaryimage"},"thumbnailUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2025\/10\/elio-2-rec.jpg","datePublished":"2026-01-14T19:22:27+00:00","dateModified":"2026-01-14T19:24:23+00:00","breadcrumb":{"@id":"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/#primaryimage","url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2025\/10\/elio-2-rec.jpg","contentUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2025\/10\/elio-2-rec.jpg","width":1400,"height":933},{"@type":"BreadcrumbList","@id":"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musica.santjosep.org\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/musica.santjosep.org\/es\/concerts\/"},{"@type":"ListItem","position":3,"name":"Elio Crispo y su espect\u00e1culo de canciones en ingl\u00e9s \u2018I Love the 80\u2019s\u2019 en Cas Costas"}]},{"@type":"WebSite","@id":"https:\/\/musica.santjosep.org\/es\/#website","url":"https:\/\/musica.santjosep.org\/es\/","name":"Sant Josep \u00e9s m\u00fasica","description":"Informaci\u00f3n actualizada de todos los conciertos, grupos y artistas que act\u00faen tanto en fiestas y festivales, como en establecimientos privados en el municipio de Sant Josep de sa Talaia","publisher":{"@id":"https:\/\/musica.santjosep.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musica.santjosep.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musica.santjosep.org\/es\/#organization","name":"Sant Josep \u00e9s m\u00fasica","url":"https:\/\/musica.santjosep.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musica.santjosep.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2022\/01\/logo-SJEM.png","contentUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2022\/01\/logo-SJEM.png","width":213,"height":103,"caption":"Sant Josep \u00e9s m\u00fasica"},"image":{"@id":"https:\/\/musica.santjosep.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790","https:\/\/x.com\/MusicaSantJosep","https:\/\/www.instagram.com\/musicasantjosep\/","https:\/\/www.youtube.com\/channel\/UCBSLSUpqfrfsiOMVslmZEJA"]}]}},"_links":{"self":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tribe_events\/54626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tribe_events\/54626\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/media\/53173"}],"wp:attachment":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/media?parent=54626"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tags?post=54626"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=54626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}