{"id":46430,"date":"2025-04-02T00:03:49","date_gmt":"2025-04-01T22:03:49","guid":{"rendered":"https:\/\/musica.santjosep.org\/?post_type=tribe_events&#038;p=46430"},"modified":"2025-04-02T00:03:49","modified_gmt":"2025-04-01T22:03:49","slug":"jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2","status":"publish","type":"tribe_events","link":"https:\/\/musica.santjosep.org\/es\/concierto\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\/","title":{"rendered":"Jam session con Albert Oliva &#038; Friends en el bar restaurante Why Not de Cala de Bou"},"content":{"rendered":"<p>Why Not, el bar restaurante de Cala de Bou, ofrece este jueves una nueva <em>jam session.<\/em> La lidera el cantante y guitarrista Albert Oliva, que estar\u00e1 acompa\u00f1ado de un nutrido grupo de m\u00fasicos amigos. Oliva es uno de los artistas m\u00e1s habituales de los escenarios de la isla y ha dirigido multitud de <em>jam session<\/em>, entre las que destacan las que se celebraban al atardecer en es Cubells, durante los veranos. Asimismo, act\u00faa con numerosos grupos, como 12 Bars All Blues, Eivissurfers, The Peluts, Around &amp; Around y otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Why Not, el bar restaurante de Cala de Bou, ofrece este jueves una nueva jam session. La lidera el cantante y guitarrista Albert Oliva, que estar\u00e1 acompa\u00f1ado de un nutrido grupo de m\u00fasicos amigos. Oliva es uno de los artistas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":45889,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[16,22],"class_list":["post-46430","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-blues","tribe_events_cat-jazz","cat_blues","cat_jazz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jam session con Albert Oliva &amp; Friends en el bar restaurante Why Not de Cala de Bou - Sant Josep \u00e9s m\u00fasica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musica.santjosep.org\/es\/concierto\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jam session con Albert Oliva &amp; Friends en el bar restaurante Why Not de Cala de Bou - Sant Josep \u00e9s m\u00fasica\" \/>\n<meta property=\"og:description\" content=\"Why Not, el bar restaurante de Cala de Bou, ofrece este jueves una nueva jam session. La lidera el cantante y guitarrista Albert Oliva, que estar\u00e1 acompa\u00f1ado de un nutrido grupo de m\u00fasicos amigos. Oliva es uno de los artistas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musica.santjosep.org\/es\/concierto\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Sant Josep \u00e9s m\u00fasica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2025\/03\/12-Bars-All-Blues.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"934\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicaSantJosep\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\\\/\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\\\/\",\"name\":\"Jam session con Albert Oliva & Friends en el bar restaurante Why Not de Cala de Bou - Sant Josep \u00e9s m\u00fasica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/12-Bars-All-Blues.jpg\",\"datePublished\":\"2025-04-01T22:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/12-Bars-All-Blues.jpg\",\"contentUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/12-Bars-All-Blues.jpg\",\"width\":1400,\"height\":934,\"caption\":\"Joan F. Ribas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concerts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jam session con Albert Oliva &#038; Friends en el bar restaurante Why Not de Cala de Bou\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\",\"name\":\"Sant Josep \u00e9s m\u00fasica\",\"description\":\"Informaci\u00f3n actualizada de todos los conciertos, grupos y artistas que act\u00faen tanto en fiestas y festivales, como en establecimientos privados en el municipio de Sant Josep de sa Talaia\",\"publisher\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#organization\",\"name\":\"Sant Josep \u00e9s m\u00fasica\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-SJEM.png\",\"contentUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-SJEM.png\",\"width\":213,\"height\":103,\"caption\":\"Sant Josep \u00e9s m\u00fasica\"},\"image\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sant-Josep-s-Msica-105337042007790\",\"https:\\\/\\\/x.com\\\/MusicaSantJosep\",\"https:\\\/\\\/www.instagram.com\\\/musicasantjosep\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBSLSUpqfrfsiOMVslmZEJA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jam session con Albert Oliva & Friends en el bar restaurante Why Not de Cala de Bou - Sant Josep \u00e9s m\u00fasica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musica.santjosep.org\/es\/concierto\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\/","og_locale":"es_ES","og_type":"article","og_title":"Jam session con Albert Oliva & Friends en el bar restaurante Why Not de Cala de Bou - Sant Josep \u00e9s m\u00fasica","og_description":"Why Not, el bar restaurante de Cala de Bou, ofrece este jueves una nueva jam session. La lidera el cantante y guitarrista Albert Oliva, que estar\u00e1 acompa\u00f1ado de un nutrido grupo de m\u00fasicos amigos. Oliva es uno de los artistas [&hellip;]","og_url":"https:\/\/musica.santjosep.org\/es\/concierto\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\/","og_site_name":"Sant Josep \u00e9s m\u00fasica","article_publisher":"https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790","og_image":[{"width":1400,"height":934,"url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2025\/03\/12-Bars-All-Blues.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicaSantJosep","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musica.santjosep.org\/es\/concierto\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\/","url":"https:\/\/musica.santjosep.org\/es\/concierto\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\/","name":"Jam session con Albert Oliva & Friends en el bar restaurante Why Not de Cala de Bou - Sant Josep \u00e9s m\u00fasica","isPartOf":{"@id":"https:\/\/musica.santjosep.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musica.santjosep.org\/es\/concierto\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\/#primaryimage"},"image":{"@id":"https:\/\/musica.santjosep.org\/es\/concierto\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\/#primaryimage"},"thumbnailUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2025\/03\/12-Bars-All-Blues.jpg","datePublished":"2025-04-01T22:03:49+00:00","breadcrumb":{"@id":"https:\/\/musica.santjosep.org\/es\/concierto\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musica.santjosep.org\/es\/concierto\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musica.santjosep.org\/es\/concierto\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\/#primaryimage","url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2025\/03\/12-Bars-All-Blues.jpg","contentUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2025\/03\/12-Bars-All-Blues.jpg","width":1400,"height":934,"caption":"Joan F. Ribas"},{"@type":"BreadcrumbList","@id":"https:\/\/musica.santjosep.org\/es\/concierto\/jam-session-con-albert-oliva-friends-en-el-bar-restaurante-why-not-de-cala-de-bou-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musica.santjosep.org\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/musica.santjosep.org\/es\/concerts\/"},{"@type":"ListItem","position":3,"name":"Jam session con Albert Oliva &#038; Friends en el bar restaurante Why Not de Cala de Bou"}]},{"@type":"WebSite","@id":"https:\/\/musica.santjosep.org\/es\/#website","url":"https:\/\/musica.santjosep.org\/es\/","name":"Sant Josep \u00e9s m\u00fasica","description":"Informaci\u00f3n actualizada de todos los conciertos, grupos y artistas que act\u00faen tanto en fiestas y festivales, como en establecimientos privados en el municipio de Sant Josep de sa Talaia","publisher":{"@id":"https:\/\/musica.santjosep.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musica.santjosep.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musica.santjosep.org\/es\/#organization","name":"Sant Josep \u00e9s m\u00fasica","url":"https:\/\/musica.santjosep.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musica.santjosep.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2022\/01\/logo-SJEM.png","contentUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2022\/01\/logo-SJEM.png","width":213,"height":103,"caption":"Sant Josep \u00e9s m\u00fasica"},"image":{"@id":"https:\/\/musica.santjosep.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790","https:\/\/x.com\/MusicaSantJosep","https:\/\/www.instagram.com\/musicasantjosep\/","https:\/\/www.youtube.com\/channel\/UCBSLSUpqfrfsiOMVslmZEJA"]}]}},"_links":{"self":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tribe_events\/46430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tribe_events\/46430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/media\/45889"}],"wp:attachment":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/media?parent=46430"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tags?post=46430"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=46430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}