{"id":39043,"date":"2024-08-08T14:51:25","date_gmt":"2024-08-08T12:51:25","guid":{"rendered":"https:\/\/musica.santjosep.org\/?post_type=tribe_events&#038;p=39043"},"modified":"2024-09-06T12:55:33","modified_gmt":"2024-09-06T10:55:33","slug":"reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station","status":"publish","type":"tribe_events","link":"https:\/\/musica.santjosep.org\/es\/concierto\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\/","title":{"rendered":"Reflection trae el rock de las caras B al escenario de Can Jordi Blues Station"},"content":{"rendered":"<p>Tras el par\u00f3n musical de agosto, vuelve la m\u00fasica en vivo a Can Jordi con el estreno en la Station de la nueva banda Reflection. La componen el holand\u00e9s Edwin Huber (voz, guitarra y arm\u00f3nica), el madrile\u00f1o Roberto Bustamante (guitarra solista), el portugu\u00e9s Armando Gra\u00e7a (bajo) y el argentino Carlos Lemmi (bater\u00eda). Ofrecen un repertorio de versiones menos conocidas de artistas muy famosos; las canciones que suelen estar en las caras B de los \u00e1lbumes. Entre ellos, Bob Dylan, Neil Young, The Rolling Stones, Jimi Hendrix, David Bowie, Lou Reed, Buffalo Springfield, The Kings\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras el par\u00f3n musical de agosto, vuelve la m\u00fasica en vivo a Can Jordi con el estreno en la Station de la nueva banda Reflection. La componen el holand\u00e9s Edwin Huber (voz, guitarra y arm\u00f3nica), el madrile\u00f1o Roberto Bustamante (guitarra [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":39028,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[15],"class_list":["post-39043","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-rock","cat_rock"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reflection trae el rock de las caras B al escenario de Can Jordi Blues Station - Sant Josep \u00e9s m\u00fasica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musica.santjosep.org\/es\/concierto\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reflection trae el rock de las caras B al escenario de Can Jordi Blues Station - Sant Josep \u00e9s m\u00fasica\" \/>\n<meta property=\"og:description\" content=\"Tras el par\u00f3n musical de agosto, vuelve la m\u00fasica en vivo a Can Jordi con el estreno en la Station de la nueva banda Reflection. La componen el holand\u00e9s Edwin Huber (voz, guitarra y arm\u00f3nica), el madrile\u00f1o Roberto Bustamante (guitarra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musica.santjosep.org\/es\/concierto\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\/\" \/>\n<meta property=\"og:site_name\" content=\"Sant Josep \u00e9s m\u00fasica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-06T10:55:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2024\/08\/Reflection-2-rec.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicaSantJosep\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\\\/\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\\\/\",\"name\":\"Reflection trae el rock de las caras B al escenario de Can Jordi Blues Station - Sant Josep \u00e9s m\u00fasica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Reflection-2-rec.jpg\",\"datePublished\":\"2024-08-08T12:51:25+00:00\",\"dateModified\":\"2024-09-06T10:55:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\\\/#primaryimage\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Reflection-2-rec.jpg\",\"contentUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Reflection-2-rec.jpg\",\"width\":1400,\"height\":933},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concierto\\\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/concerts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reflection trae el rock de las caras B al escenario de Can Jordi Blues Station\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\",\"name\":\"Sant Josep \u00e9s m\u00fasica\",\"description\":\"Informaci\u00f3n actualizada de todos los conciertos, grupos y artistas que act\u00faen tanto en fiestas y festivales, como en establecimientos privados en el municipio de Sant Josep de sa Talaia\",\"publisher\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#organization\",\"name\":\"Sant Josep \u00e9s m\u00fasica\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-SJEM.png\",\"contentUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-SJEM.png\",\"width\":213,\"height\":103,\"caption\":\"Sant Josep \u00e9s m\u00fasica\"},\"image\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sant-Josep-s-Msica-105337042007790\",\"https:\\\/\\\/x.com\\\/MusicaSantJosep\",\"https:\\\/\\\/www.instagram.com\\\/musicasantjosep\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBSLSUpqfrfsiOMVslmZEJA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reflection trae el rock de las caras B al escenario de Can Jordi Blues Station - Sant Josep \u00e9s m\u00fasica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musica.santjosep.org\/es\/concierto\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\/","og_locale":"es_ES","og_type":"article","og_title":"Reflection trae el rock de las caras B al escenario de Can Jordi Blues Station - Sant Josep \u00e9s m\u00fasica","og_description":"Tras el par\u00f3n musical de agosto, vuelve la m\u00fasica en vivo a Can Jordi con el estreno en la Station de la nueva banda Reflection. La componen el holand\u00e9s Edwin Huber (voz, guitarra y arm\u00f3nica), el madrile\u00f1o Roberto Bustamante (guitarra [&hellip;]","og_url":"https:\/\/musica.santjosep.org\/es\/concierto\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\/","og_site_name":"Sant Josep \u00e9s m\u00fasica","article_publisher":"https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790","article_modified_time":"2024-09-06T10:55:33+00:00","og_image":[{"width":1400,"height":933,"url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2024\/08\/Reflection-2-rec.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicaSantJosep","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musica.santjosep.org\/es\/concierto\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\/","url":"https:\/\/musica.santjosep.org\/es\/concierto\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\/","name":"Reflection trae el rock de las caras B al escenario de Can Jordi Blues Station - Sant Josep \u00e9s m\u00fasica","isPartOf":{"@id":"https:\/\/musica.santjosep.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musica.santjosep.org\/es\/concierto\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\/#primaryimage"},"image":{"@id":"https:\/\/musica.santjosep.org\/es\/concierto\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\/#primaryimage"},"thumbnailUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2024\/08\/Reflection-2-rec.jpg","datePublished":"2024-08-08T12:51:25+00:00","dateModified":"2024-09-06T10:55:33+00:00","breadcrumb":{"@id":"https:\/\/musica.santjosep.org\/es\/concierto\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musica.santjosep.org\/es\/concierto\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musica.santjosep.org\/es\/concierto\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\/#primaryimage","url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2024\/08\/Reflection-2-rec.jpg","contentUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2024\/08\/Reflection-2-rec.jpg","width":1400,"height":933},{"@type":"BreadcrumbList","@id":"https:\/\/musica.santjosep.org\/es\/concierto\/reflection-trae-el-rock-de-las-caras-b-al-escenario-de-can-jordi-blues-station\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musica.santjosep.org\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/musica.santjosep.org\/es\/concerts\/"},{"@type":"ListItem","position":3,"name":"Reflection trae el rock de las caras B al escenario de Can Jordi Blues Station"}]},{"@type":"WebSite","@id":"https:\/\/musica.santjosep.org\/es\/#website","url":"https:\/\/musica.santjosep.org\/es\/","name":"Sant Josep \u00e9s m\u00fasica","description":"Informaci\u00f3n actualizada de todos los conciertos, grupos y artistas que act\u00faen tanto en fiestas y festivales, como en establecimientos privados en el municipio de Sant Josep de sa Talaia","publisher":{"@id":"https:\/\/musica.santjosep.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musica.santjosep.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musica.santjosep.org\/es\/#organization","name":"Sant Josep \u00e9s m\u00fasica","url":"https:\/\/musica.santjosep.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musica.santjosep.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2022\/01\/logo-SJEM.png","contentUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2022\/01\/logo-SJEM.png","width":213,"height":103,"caption":"Sant Josep \u00e9s m\u00fasica"},"image":{"@id":"https:\/\/musica.santjosep.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790","https:\/\/x.com\/MusicaSantJosep","https:\/\/www.instagram.com\/musicasantjosep\/","https:\/\/www.youtube.com\/channel\/UCBSLSUpqfrfsiOMVslmZEJA"]}]}},"_links":{"self":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tribe_events\/39043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tribe_events\/39043\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/media\/39028"}],"wp:attachment":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/media?parent=39043"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tags?post=39043"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=39043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}