{"id":29409,"date":"2023-11-14T22:31:21","date_gmt":"2023-11-14T21:31:21","guid":{"rendered":"https:\/\/musica.santjosep.org\/?post_type=musicos&#038;p=29409"},"modified":"2023-11-20T19:30:55","modified_gmt":"2023-11-20T18:30:55","slug":"elio-crispo","status":"publish","type":"musicos","link":"https:\/\/musica.santjosep.org\/es\/musicos\/elio-crispo\/","title":{"rendered":"Elio Crispo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"edgtf-image-gallery  edgtf-ig-slider-type edgtf-large-space  \">\n\t<div class=\"edgtf-ig-slider edgtf-owl-slider\" data-number-of-items=\"1\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-slider-padding=\"no\" data-enable-navigation=\"yes\" data-enable-pagination=\"yes\">\n\t\t\t\t\t<div class=\"edgtf-ig-image\">\n\t\t\t\t\t\t\t\t\t<div class=\"edgtf-image-with-caption\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"933\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-2-rec.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-2-rec.jpg 1400w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-2-rec-300x200.jpg 300w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-2-rec-1024x682.jpg 1024w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-2-rec-768x512.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"edgtf-custom-caption\">Ximena Topolansky<\/div><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-ig-image\">\n\t\t\t\t\t\t\t\t\t<div class=\"edgtf-image-with-caption\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"933\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-1-rec.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-1-rec.jpg 1400w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-1-rec-300x200.jpg 300w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-1-rec-1024x682.jpg 1024w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-1-rec-768x512.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"edgtf-custom-caption\">Ximena Topolansky<\/div><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-ig-image\">\n\t\t\t\t\t\t\t\t\t<div class=\"edgtf-image-with-caption\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"933\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-4-rec.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-4-rec.jpg 1400w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-4-rec-300x200.jpg 300w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-4-rec-1024x682.jpg 1024w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-4-rec-768x512.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"edgtf-custom-caption\">Monica Ciocolonni<\/div><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-ig-image\">\n\t\t\t\t\t\t\t\t\t<div class=\"edgtf-image-with-caption\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"933\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-3-rec.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-3-rec.jpg 1400w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-3-rec-300x200.jpg 300w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-3-rec-1024x682.jpg 1024w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-3-rec-768x512.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"edgtf-custom-caption\">Ximena Topolansky<\/div><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-ig-image\">\n\t\t\t\t\t\t\t\t\t<div class=\"edgtf-image-with-caption\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"932\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-5-rec.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-5-rec.jpg 1400w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-5-rec-300x200.jpg 300w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-5-rec-1024x682.jpg 1024w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-5-rec-768x511.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><div class=\"edgtf-custom-caption\">Monica Ciocolonni<\/div><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"edgtf-ig-image\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"933\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-camdombe-rec.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-camdombe-rec.jpg 1400w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-camdombe-rec-300x200.jpg 300w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-camdombe-rec-1024x682.jpg 1024w, https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-camdombe-rec-768x512.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row el_id=\u00bbb2musico\u00bb][vc_column width=\u00bb1\/3&#8243;][vc_column_text]<div class=\"titsmall\">Contacto<\/div><a href=\"tel:+34626 907 777\" target=\"_blank\" class=\"campoficha w100\">626 907 777<\/a><div class=\"titsmall\">Redes<\/div><a href=\"https:\/\/www.facebook.com\/elio.crispo\" target=\"_blank\" class=\"campoficha\" ><span class=\"fab fa-facebook\"><\/span><\/a><a href=\"https:\/\/www.facebook.com\/elio.crispo\" target=\"_blank\" class=\"campoficha\"><span class=\"fab fa-instagram\"><\/span><\/a><div class=\"titsmall\">Plataformas<\/div><a href=\"https:\/\/www.youtube.com\/channel\/UCk0myl0Gd4N1HBl8t7aHjag\" target=\"_blank\" class=\"campoficha\" data-tooltip=\"YouTube\"><span class=\"fab fa-youtube\"><\/span><\/a><a href=\"https:\/\/open.spotify.com\/intl-es\/artist\/1Z1ZML3dEPEE2NeNfc6Te5?si=3fL3FsNtSX-Zm4AzJgufcA\" target=\"_blank\" class=\"campoficha\" data-tooltip=\"Spotify\"><span class=\"fab fa-spotify\"><\/span><\/a><a href=\"https:\/\/music.apple.com\/es\/artist\/eleonora-crispo-elio\/1715767431\" target=\"_blank\" class=\"campoficha\" data-tooltip=\"Apple Music\"><span class=\"fab fa-apple\"><\/span><\/a><a href=\"https:\/\/music.amazon.es\/artists\/B0CMZHH9XL\/eleonora-crispo-elio\" target=\"_blank\" class=\"campoficha\" data-tooltip=\"Amazon Music\"><span class=\"fab fa-amazon\"><\/span><\/a><a href=\"https:\/\/elioalive.bandcamp.com\" target=\"_blank\" class=\"campoficha\" data-tooltip=\"Bandcamp\"><span class=\"fab fa-bandcamp\"><\/span><\/a><a href=\"https:\/\/www.deezer.com\/en\/artist\/242817621\" target=\"_blank\" class=\"campoficha\" data-tooltip=\"Deezer\"><span class=\"micon-deezer\"><\/span><\/a>[\/vc_column_text][vc_column_text]<div class=\"container enfunc\" id=\"eventos_rel_bymusico\">\n\t\t\t\t<h2 class=\"titsmall\">Pr\u00f3ximos conciertos<\/h2>\n\t\t\t\t<div class=\"vc_row-fluid\"><div class=\"tarjevent\"><a href=\"https:\/\/musica.santjosep.org\/es\/concert\/elio-crispo-y-su-espectaculo-i-love-the-80s-en-el-escenario-de-cas-costas\/2026-05-14\/\" class=\"img_event_content\">\n\t\t\t\t\t\t\t\t<div class=\"tribe-event-schedule-details\">\n\t\t\t\t\t\t\t\t\t<span class=\"e-dia\">14<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"e-mes\">May<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2026\/05\/elio-2-rec.jpg\">\n\t\t\t\t\t\t\t\t<\/a><div class=\"tribe-events-event-details tribe-clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"tribe-events-event-meta\">\n\t\t\t\t\t\t\t\t\tCas Costas\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<h3 class=\"tribe-events-list-event-title\">\n\t\t\t\t\t\t\t\t\t<a class=\"tribe-event-url\" href=\"https:\/\/musica.santjosep.org\/es\/concert\/elio-crispo-y-su-espectaculo-i-love-the-80s-en-el-escenario-de-cas-costas\/2026-05-14\/\" title=\"\" rel=\"bookmark\">Elio Crispo y su espect\u00e1culo \u2018I Love the 80\u2019s\u2019, en el escenario de Cas Costas<\/a>\n\t\t\t\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div><div class=\"tarjevent\"><a href=\"https:\/\/musica.santjosep.org\/es\/concert\/elio-crispo-y-su-espectaculo-i-love-the-80s-en-el-escenario-de-cas-costas\/2026-06-04\/\" class=\"img_event_content\">\n\t\t\t\t\t\t\t\t<div class=\"tribe-event-schedule-details\">\n\t\t\t\t\t\t\t\t\t<span class=\"e-dia\">04<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"e-mes\">Jun<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2026\/05\/elio-2-rec.jpg\">\n\t\t\t\t\t\t\t\t<\/a><div class=\"tribe-events-event-details tribe-clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"tribe-events-event-meta\">\n\t\t\t\t\t\t\t\t\tCas Costas\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<h3 class=\"tribe-events-list-event-title\">\n\t\t\t\t\t\t\t\t\t<a class=\"tribe-event-url\" href=\"https:\/\/musica.santjosep.org\/es\/concert\/elio-crispo-y-su-espectaculo-i-love-the-80s-en-el-escenario-de-cas-costas\/2026-06-04\/\" title=\"\" rel=\"bookmark\">Elio Crispo y su espect\u00e1culo \u2018I Love the 80\u2019s\u2019, en el escenario de Cas Costas<\/a>\n\t\t\t\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div><div class=\"tarjevent\"><a href=\"https:\/\/musica.santjosep.org\/es\/concert\/elio-crispo-y-su-espectaculo-i-love-the-80s-en-el-escenario-de-cas-costas\/2026-08-13\/\" class=\"img_event_content\">\n\t\t\t\t\t\t\t\t<div class=\"tribe-event-schedule-details\">\n\t\t\t\t\t\t\t\t\t<span class=\"e-dia\">13<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"e-mes\">Ago<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2026\/05\/elio-2-rec.jpg\">\n\t\t\t\t\t\t\t\t<\/a><div class=\"tribe-events-event-details tribe-clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"tribe-events-event-meta\">\n\t\t\t\t\t\t\t\t\tCas Costas\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<h3 class=\"tribe-events-list-event-title\">\n\t\t\t\t\t\t\t\t\t<a class=\"tribe-event-url\" href=\"https:\/\/musica.santjosep.org\/es\/concert\/elio-crispo-y-su-espectaculo-i-love-the-80s-en-el-escenario-de-cas-costas\/2026-08-13\/\" title=\"\" rel=\"bookmark\">Elio Crispo y su espect\u00e1culo \u2018I Love the 80\u2019s\u2019, en el escenario de Cas Costas<\/a>\n\t\t\t\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div><\/div><\/div><div class=\"container enfunc\" id=\"eventos_rel_bymusico_pas\">\n\t\t\t\t<h2 class=\"titsmall\">Eventos pasados<\/h2>\n\t\t\t\t<div class=\"vc_row-fluid\"><div class=\"tarjevent\"><a href=\"https:\/\/musica.santjosep.org\/es\/concert\/elio-crispo-vuelve-con-su-espectaculo-i-love-the-80s-al-escenario-de-cas-costas\/2026-04-23\/\" class=\"img_event_content\">\n\t\t\t\t\t\t\t\t<div class=\"tribe-event-schedule-details\">\n\t\t\t\t\t\t\t\t\t<span class=\"e-dia\">23<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"e-mes\">Abr<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2026\/03\/Elio-Crispo-1-rec.jpg\">\n\t\t\t\t\t\t\t\t<\/a><div class=\"tribe-events-event-details tribe-clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"tribe-events-event-meta\">\n\t\t\t\t\t\t\t\t\tCas Costas\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<h3 class=\"tribe-events-list-event-title\">\n\t\t\t\t\t\t\t\t\t<a class=\"tribe-event-url\" href=\"https:\/\/musica.santjosep.org\/es\/concert\/elio-crispo-vuelve-con-su-espectaculo-i-love-the-80s-al-escenario-de-cas-costas\/2026-04-23\/\" title=\"\" rel=\"bookmark\">Elio Crispo vuelve con su espect\u00e1culo \u2018I Love the 80\u2019s\u2019 al escenario de Cas Costas<\/a>\n\t\t\t\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div><div class=\"tarjevent\"><a href=\"https:\/\/musica.santjosep.org\/es\/concert\/elio-crispo-vuelve-con-su-espectaculo-i-love-the-80s-al-escenario-de-cas-costas\/2026-03-26\/\" class=\"img_event_content\">\n\t\t\t\t\t\t\t\t<div class=\"tribe-event-schedule-details\">\n\t\t\t\t\t\t\t\t\t<span class=\"e-dia\">26<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"e-mes\">Mar<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2026\/03\/Elio-Crispo-1-rec.jpg\">\n\t\t\t\t\t\t\t\t<\/a><div class=\"tribe-events-event-details tribe-clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"tribe-events-event-meta\">\n\t\t\t\t\t\t\t\t\tCas Costas\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<h3 class=\"tribe-events-list-event-title\">\n\t\t\t\t\t\t\t\t\t<a class=\"tribe-event-url\" href=\"https:\/\/musica.santjosep.org\/es\/concert\/elio-crispo-vuelve-con-su-espectaculo-i-love-the-80s-al-escenario-de-cas-costas\/2026-03-26\/\" title=\"\" rel=\"bookmark\">Elio Crispo vuelve con su espect\u00e1culo \u2018I Love the 80\u2019s\u2019 al escenario de Cas Costas<\/a>\n\t\t\t\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div><div class=\"tarjevent\"><a href=\"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/\" class=\"img_event_content\">\n\t\t\t\t\t\t\t\t<div class=\"tribe-event-schedule-details\">\n\t\t\t\t\t\t\t\t\t<span class=\"e-dia\">15<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"e-mes\">Ene<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2025\/10\/elio-2-rec.jpg\">\n\t\t\t\t\t\t\t\t<\/a><div class=\"tribe-events-event-details tribe-clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"tribe-events-event-meta\">\n\t\t\t\t\t\t\t\t\tCas Costas\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<h3 class=\"tribe-events-list-event-title\">\n\t\t\t\t\t\t\t\t\t<a class=\"tribe-event-url\" href=\"https:\/\/musica.santjosep.org\/es\/concierto\/elio-crispo-y-su-espectaculo-de-canciones-en-ingles-i-love-the-80s-en-cas-costas-2\/\" title=\"\" rel=\"bookmark\">Elio Crispo y su espect\u00e1culo de canciones en ingl\u00e9s \u2018I Love the 80\u2019s\u2019 en Cas Costas<\/a>\n\t\t\t\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div><\/div><\/div>[\/vc_column_text][\/vc_column][vc_column width=\u00bb2\/3&#8243;][vc_column_text el_class=\u00bbtexto_musico\u00bb]Eleonora Crispo, <em>Elio<\/em>, es una de las cantantes de tango m\u00e1s prestigiosas de Ibiza, aunque maneja otros g\u00e9neros musicales, como el pop, el soul y el jazz, y tiene gran capacidad para la improvisaci\u00f3n. Naci\u00f3 en Buenos Aires (1976), de padres uruguayos, aunque regres\u00f3 al Uruguay de peque\u00f1a, donde se crio con su abuela paterna, que se pasaba los d\u00edas escuchando a Gardel. Se traslad\u00f3 a Ibiza hace ya m\u00e1s de veinte a\u00f1os y, aunque siempre le ha apasionado la m\u00fasica, nunca se hab\u00eda dedicado profesionalmente a ella. Fue una cuesti\u00f3n de salud, un problema en la tiroides, lo que le empuj\u00f3 a cantar porque intu\u00eda que a trav\u00e9s de ello encontrar\u00eda un camino para reequilibrar su vitalidad, como finalmente logr\u00f3.<\/p>\n<p>Comenz\u00f3 a dedicarse profesionalmente a la m\u00fasica en 2012 y, en 2018, actu\u00f3 y grab\u00f3 una balada de jazz para el cortometraje \u2018167 jours et 4 heures\u2019, de Alain Deymier. En el mismo a\u00f1o, viaj\u00f3 a Viena para interpretar unas piezas de tango, acompa\u00f1ada por el gran pianista Elias Meiri. En aquella \u00e9poca, sin embargo, interpretaba sobre todo pop y soul en ingl\u00e9s, sumergi\u00e9ndose en la m\u00fasica con tal intensidad que, en 2019, grab\u00f3 su primer \u00e1lbum, <em>I\u2019m alive<\/em>. Constituye un himno a la fuerza interior, con canciones de su creaci\u00f3n que reflejan su resiliencia y mentalidad positiva. Fue una \u00e9poca en la que tambi\u00e9n profundiz\u00f3 en la improvisaci\u00f3n con la voz, grabando varios trabajos en el estudio de Robert Arat\u00f3.<\/p>\n<p>Ya en 2022, se meti\u00f3 de lleno en el tango empujada por sus amigos, que se emocionaban cuando se los escuchaban cantar en petit comit\u00e9. A continuaci\u00f3n, fund\u00f3 el d\u00fao <a href=\"https:\/\/musica.santjosep.org\/es\/musicos\/mano-a-mano\/\" target=\"_blank\" rel=\"noopener\">Mano a mano<\/a>, que hoy por hoy ya es uno de los m\u00e1s habituales en los escenarios de la isla, en el que ella canta y el bonaerense Claudio C\u00e9sar le acompa\u00f1a a la guitarra. Adem\u00e1s, Elio es percusionista de tambor uruguayo de candombe, con el que suele actuar en eventos privados.[\/vc_column_text][vc_row_inner][vc_column_inner][vc_column_text]<div id=\"bdiscos\" class=\"discosenmusico\"><div class=\"titsmall\">discos<\/div><div class=\"item_disco\">\n\t\t\t\t\t<a href=\"https:\/\/musica.santjosep.org\/es\/discos\/im-alive\/\" class=\"bidisco\"><img decoding=\"async\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/portada-rec.jpg\"><\/a>\n\t\t\t\t\t<div class=\"rightdisco\">\n\t\t\t\t\t\t<p><span class=\"\">Elio Crispo<\/span><span><\/span><\/p>\n\t\t\t\t\t\t<h3>I\u2019m alive<\/h3>\n\t\t\t\t\t\t<div class=\"btext\">Con este \u00e1lbum, la hoy cantante de tangos Eleonora Crispo inicio su carrera. Incluye siete canciones de pop y soul en ingl\u00e9s, compuestas por ella (2019). <\/div><a href=\"https:\/\/musica.santjosep.org\/es\/discos\/im-alive\/\" class=\"link_play\"><i class=\"fa fa-play-circle\"><\/i><span>Escucha el disco<\/span><\/a><\/div>\n\t\t\t\t<\/div><div class=\"item_disco\">\n\t\t\t\t\t<a href=\"https:\/\/musica.santjosep.org\/es\/discos\/the-unknown\/\" class=\"bidisco\"><img decoding=\"async\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/Captura-de-Pantalla-2023-11-15-a-las-10.26.35.jpg\"><\/a>\n\t\t\t\t\t<div class=\"rightdisco\">\n\t\t\t\t\t\t<p><span class=\"\">Elio Crispo<\/span><span><\/span><\/p>\n\t\t\t\t\t\t<h3>The Unknown<\/h3>\n\t\t\t\t\t\t<div class=\"btext\">Primer \u00e1lbum de improvisaci\u00f3n vocal y piano grabado por Elio Crispo y Robert Arat\u00f3, en los estudios ibicencos Bluehill, en 2020.<\/div><a href=\"https:\/\/musica.santjosep.org\/es\/discos\/the-unknown\/\" class=\"link_play\"><i class=\"fa fa-play-circle\"><\/i><span>Escucha el disco<\/span><\/a><\/div>\n\t\t\t\t<\/div><div class=\"item_disco\">\n\t\t\t\t\t<a href=\"https:\/\/musica.santjosep.org\/es\/discos\/new-beginning\/\" class=\"bidisco\"><img decoding=\"async\" src=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-15-at-10.10.09.jpeg\"><\/a>\n\t\t\t\t\t<div class=\"rightdisco\">\n\t\t\t\t\t\t<p><span class=\"\">Elio Crispo<\/span><span><\/span><\/p>\n\t\t\t\t\t\t<h3>New Beginning<\/h3>\n\t\t\t\t\t\t<div class=\"btext\">Segundo trabajo de improvisaci\u00f3n de la cantante Elio Crispo y el teclista Robert Arat\u00f3, grabado en los Bluehill Studios de Ibiza, en 2023.<\/div><a href=\"https:\/\/musica.santjosep.org\/es\/discos\/new-beginning\/\" class=\"link_play\"><i class=\"fa fa-play-circle\"><\/i><span>Escucha el disco<\/span><\/a><\/div>\n\t\t\t\t<\/div><\/div>[\/vc_column_text][vc_column_text el_class=\u00bbtitsmall\u00bb]Videos[\/vc_column_text][vc_video link=\u00bbhttps:\/\/youtu.be\/-0mIw4wQn_o?si=FCutjPuZn3y42hU9&#8243; title=\u00bb&#8216;Como dos extra\u00f1os&#8217; (Mano a mano)\u00bb][vc_video link=\u00bbhttps:\/\/youtu.be\/qpg202fWijg?si=BmcF1BuCPNqvD7Ml\u00bb title=\u00bb\u2018I\u2019m Alive\u2019\u00bb][vc_video link=\u00bbhttps:\/\/www.youtube.com\/watch?v=m7zunD-WQ1A\u00bb title=\u00bb\u2018Inside a Room\u2019 (167 jours et 4 heures)\u00bb][\/vc_column_inner][\/vc_row_inner][vc_column_text el_class=\u00bblinkvertodos\u00bb]<a href=\"https:\/\/musica.santjosep.org\/es\/musicos-santjosep\/\">Ver todos los m\u00fasicos de Sant Josep<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Vocalista y compositora de origen argentino, afincada en Ibiza desde hace m\u00e1s de veinte a\u00f1os, dedicada al pop, el soul, el jazz y el tango.<\/p>\n","protected":false},"author":2,"featured_media":29412,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"class_list":["post-29409","musicos","type-musicos","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elio Crispo - Sant Josep \u00e9s m\u00fasica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musica.santjosep.org\/es\/musicos\/elio-crispo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elio Crispo - Sant Josep \u00e9s m\u00fasica\" \/>\n<meta property=\"og:description\" content=\"Vocalista y compositora de origen argentino, afincada en Ibiza desde hace m\u00e1s de veinte a\u00f1os, dedicada al pop, el soul, el jazz y el tango.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musica.santjosep.org\/es\/musicos\/elio-crispo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sant Josep \u00e9s m\u00fasica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-20T18:30:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-2-rec.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicaSantJosep\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/musicos\\\/elio-crispo\\\/\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/musicos\\\/elio-crispo\\\/\",\"name\":\"Elio Crispo - Sant Josep \u00e9s m\u00fasica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/musicos\\\/elio-crispo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/musicos\\\/elio-crispo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/elio-2-rec.jpg\",\"datePublished\":\"2023-11-14T21:31:21+00:00\",\"dateModified\":\"2023-11-20T18:30:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/musicos\\\/elio-crispo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/musicos\\\/elio-crispo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/musicos\\\/elio-crispo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/elio-2-rec.jpg\",\"contentUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/elio-2-rec.jpg\",\"width\":1400,\"height\":933,\"caption\":\"Ximena Topolansky\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/musicos\\\/elio-crispo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00fasicos\",\"item\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/musicos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Elio Crispo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\",\"name\":\"Sant Josep \u00e9s m\u00fasica\",\"description\":\"Informaci\u00f3n actualizada de todos los conciertos, grupos y artistas que act\u00faen tanto en fiestas y festivales, como en establecimientos privados en el municipio de Sant Josep de sa Talaia\",\"publisher\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#organization\",\"name\":\"Sant Josep \u00e9s m\u00fasica\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-SJEM.png\",\"contentUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-SJEM.png\",\"width\":213,\"height\":103,\"caption\":\"Sant Josep \u00e9s m\u00fasica\"},\"image\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sant-Josep-s-Msica-105337042007790\",\"https:\\\/\\\/x.com\\\/MusicaSantJosep\",\"https:\\\/\\\/www.instagram.com\\\/musicasantjosep\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBSLSUpqfrfsiOMVslmZEJA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elio Crispo - Sant Josep \u00e9s m\u00fasica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musica.santjosep.org\/es\/musicos\/elio-crispo\/","og_locale":"es_ES","og_type":"article","og_title":"Elio Crispo - Sant Josep \u00e9s m\u00fasica","og_description":"Vocalista y compositora de origen argentino, afincada en Ibiza desde hace m\u00e1s de veinte a\u00f1os, dedicada al pop, el soul, el jazz y el tango.","og_url":"https:\/\/musica.santjosep.org\/es\/musicos\/elio-crispo\/","og_site_name":"Sant Josep \u00e9s m\u00fasica","article_publisher":"https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790","article_modified_time":"2023-11-20T18:30:55+00:00","og_image":[{"width":1400,"height":933,"url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-2-rec.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicaSantJosep","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musica.santjosep.org\/es\/musicos\/elio-crispo\/","url":"https:\/\/musica.santjosep.org\/es\/musicos\/elio-crispo\/","name":"Elio Crispo - Sant Josep \u00e9s m\u00fasica","isPartOf":{"@id":"https:\/\/musica.santjosep.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musica.santjosep.org\/es\/musicos\/elio-crispo\/#primaryimage"},"image":{"@id":"https:\/\/musica.santjosep.org\/es\/musicos\/elio-crispo\/#primaryimage"},"thumbnailUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-2-rec.jpg","datePublished":"2023-11-14T21:31:21+00:00","dateModified":"2023-11-20T18:30:55+00:00","breadcrumb":{"@id":"https:\/\/musica.santjosep.org\/es\/musicos\/elio-crispo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musica.santjosep.org\/es\/musicos\/elio-crispo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musica.santjosep.org\/es\/musicos\/elio-crispo\/#primaryimage","url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-2-rec.jpg","contentUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/11\/elio-2-rec.jpg","width":1400,"height":933,"caption":"Ximena Topolansky"},{"@type":"BreadcrumbList","@id":"https:\/\/musica.santjosep.org\/es\/musicos\/elio-crispo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musica.santjosep.org\/es\/"},{"@type":"ListItem","position":2,"name":"M\u00fasicos","item":"https:\/\/musica.santjosep.org\/es\/musicos\/"},{"@type":"ListItem","position":3,"name":"Elio Crispo"}]},{"@type":"WebSite","@id":"https:\/\/musica.santjosep.org\/es\/#website","url":"https:\/\/musica.santjosep.org\/es\/","name":"Sant Josep \u00e9s m\u00fasica","description":"Informaci\u00f3n actualizada de todos los conciertos, grupos y artistas que act\u00faen tanto en fiestas y festivales, como en establecimientos privados en el municipio de Sant Josep de sa Talaia","publisher":{"@id":"https:\/\/musica.santjosep.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musica.santjosep.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musica.santjosep.org\/es\/#organization","name":"Sant Josep \u00e9s m\u00fasica","url":"https:\/\/musica.santjosep.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musica.santjosep.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2022\/01\/logo-SJEM.png","contentUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2022\/01\/logo-SJEM.png","width":213,"height":103,"caption":"Sant Josep \u00e9s m\u00fasica"},"image":{"@id":"https:\/\/musica.santjosep.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790","https:\/\/x.com\/MusicaSantJosep","https:\/\/www.instagram.com\/musicasantjosep\/","https:\/\/www.youtube.com\/channel\/UCBSLSUpqfrfsiOMVslmZEJA"]}]}},"_links":{"self":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/musicos\/29409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/musicos"}],"about":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/types\/musicos"}],"author":[{"embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/musicos\/29409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/media\/29412"}],"wp:attachment":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/media?parent=29409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/categories?post=29409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}