{"id":19135,"date":"2023-03-03T10:29:07","date_gmt":"2023-03-03T09:29:07","guid":{"rendered":"https:\/\/musica.santjosep.org\/discos\/oscuro-baile-de-salon\/"},"modified":"2023-03-03T10:50:26","modified_gmt":"2023-03-03T09:50:26","slug":"oscuro-baile-de-salon","status":"publish","type":"discos","link":"https:\/\/musica.santjosep.org\/es\/discos\/oscuro-baile-de-salon\/","title":{"rendered":"Oscuro baile de sal\u00f3n"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row el_id=\u00bbbdisco\u00bb][vc_column][vc_column_text]Segundo trabajo discogr\u00e1fico de la banda ibicenca Billy Flamingos, compuesto por doce temas propios, grabados bajo la producci\u00f3n de Omar Gisbert, con Guille Podevin (voz y guitarra), Mariano Costa (guitarra), Adri\u00e1n Pedreira (bajo) y Miquel Serra (bater\u00eda) en el estudio. Ofrece un sonido rockero, blusero por momentos y \u00e1spero, que ya estaba en su primer \u00e1lbum, aunque con una producci\u00f3n salpicada de matices. El disco se lanz\u00f3 casi single a single, con siete adelantos, hasta publicar la versi\u00f3n completa en marzo de 2023. La impactante ilustraci\u00f3n de la portada es obra de Ricard Bofill.[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_id=\u00bbbcancionesdisco\u00bb][vc_column][vc_column_text el_class=\u00bbtitsmall\u00bb]Canciones[\/vc_column_text][vc_column_text]01 Avanzar<br \/>\n02 Una historia violenta<br \/>\n03 Estanque euforia<br \/>\n04 Malas intenciones<br \/>\n05 Utop\u00eda<br \/>\n06 Algo indefinido<br \/>\n07 Twist salvaje<br \/>\n08 Nada que hacer<br \/>\n09 Incendios<br \/>\n10 Dos catorce<br \/>\n11 Presente continuo<br \/>\n12 Vor\u00e1gine[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<div class=\"escucha_disco\">\n\t\t\t<div class=\"fa fa-play-circle\"><\/div>\n\t\t\t<div class=\"titsmall\">Escuchar<\/div><a href=\"https:\/\/open.spotify.com\/album\/7iPt407kDh4HPwEoTwUMtj?si=yKmPn1BcRpOfYFlRzmid7w\" target=\"_blank\" class=\"campoficha\" data-tooltip=\"Spotify\"><span class=\"fab fa-spotify\"><\/span><\/a><a href=\"https:\/\/music.amazon.es\/albums\/B0BSB4ZPDY\" target=\"_blank\" class=\"campoficha\" data-tooltip=\"Amazon Music\"><span class=\"fab fa-amazon\"><\/span><\/a><a href=\"https:\/\/music.apple.com\/us\/album\/oscuro-baile-de-sal%C3%B3n\/1665408923\" target=\"_blank\" class=\"campoficha\" data-tooltip=\"Apple Music\"><span class=\"fab fa-apple\"><\/span><\/a><a href=\"https:\/\/www.deezer.com\/en\/album\/396448717\" target=\"_blank\" class=\"campoficha\" data-tooltip=\"Deezer\"><span class=\"micon-deezer deesdisco\"><\/span><\/a><\/div><div class=\"iframe_spo\"><iframe style=\"border-radius:12px\" src=\"https:\/\/open.spotify.com\/embed\/album\/7iPt407kDh4HPwEoTwUMtj?utm_source=generator\" width=\"100%\" height=\"380\" frameBorder=\"0\" allowfullscreen=\"\" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\"><\/iframe><\/div>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_id=\u00bbbvideosdisco\u00bb][vc_column][vc_column_text el_class=\u00bbtitsmall\u00bb]Videos[\/vc_column_text][vc_video link=\u00bbhttps:\/\/youtu.be\/tFfItQp0_TM\u00bb title=\u00bb\u2018Estanque euforia\u2019 (v\u00eddeo oficial)\u00bb][vc_video link=\u00bbhttps:\/\/youtu.be\/IlUgbx8d_pw\u00bb title=\u00bb\u2018Nada que hacer\u2019 (v\u00eddeo oficial)\u00bb][vc_video link=\u00bbhttps:\/\/youtu.be\/ACi4CsqivA4&#8243; title=\u00bb\u2018Una historia violenta\u2019 (v\u00eddeo oficial)\u00bb][vc_video link=\u00bbhttps:\/\/youtu.be\/XJukAYeZGdE\u00bb title=\u00bb\u2018Malas intenciones\u2019 (v\u00eddeo oficial)\u00bb][vc_video link=\u00bbhttps:\/\/youtu.be\/DMjLhaGLiig\u00bb title=\u00bb\u2018Twist salvaje\u2019\u00bb][vc_video link=\u00bbhttps:\/\/youtu.be\/2C_zRM8eyPE\u00bb title=\u00bb\u2018Algo indefinido\u2019\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text el_class=\u00bblinkvertodos\u00bb]<a href=\"https:\/\/musica.santjosep.org\/es\/discos-santjosep\/\">Ver todos los discos<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Segundo \u00e1lbum del grupo de rock ibicenco Billy Flamingos, publicado en 2023. Incluye doce temas propios, producidos por Omar Gisbert.<\/p>\n","protected":false},"author":2,"featured_media":19132,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"class_list":["post-19135","discos","type-discos","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oscuro baile de sal\u00f3n - Sant Josep \u00e9s m\u00fasica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musica.santjosep.org\/es\/discos\/oscuro-baile-de-salon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oscuro baile de sal\u00f3n - Sant Josep \u00e9s m\u00fasica\" \/>\n<meta property=\"og:description\" content=\"Segundo \u00e1lbum del grupo de rock ibicenco Billy Flamingos, publicado en 2023. Incluye doce temas propios, producidos por Omar Gisbert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musica.santjosep.org\/es\/discos\/oscuro-baile-de-salon\/\" \/>\n<meta property=\"og:site_name\" content=\"Sant Josep \u00e9s m\u00fasica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-03T09:50:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/03\/Portada-Oscuro-baile-de-salon-1-1024x1024-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusicaSantJosep\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/discos\\\/oscuro-baile-de-salon\\\/\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/discos\\\/oscuro-baile-de-salon\\\/\",\"name\":\"Oscuro baile de sal\u00f3n - Sant Josep \u00e9s m\u00fasica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/discos\\\/oscuro-baile-de-salon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/discos\\\/oscuro-baile-de-salon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Portada-Oscuro-baile-de-salon-1-1024x1024-1.jpeg\",\"datePublished\":\"2023-03-03T09:29:07+00:00\",\"dateModified\":\"2023-03-03T09:50:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/discos\\\/oscuro-baile-de-salon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/discos\\\/oscuro-baile-de-salon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/discos\\\/oscuro-baile-de-salon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Portada-Oscuro-baile-de-salon-1-1024x1024-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Portada-Oscuro-baile-de-salon-1-1024x1024-1.jpeg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/discos\\\/oscuro-baile-de-salon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Discos\",\"item\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/discos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oscuro baile de sal\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\",\"name\":\"Sant Josep \u00e9s m\u00fasica\",\"description\":\"Informaci\u00f3n actualizada de todos los conciertos, grupos y artistas que act\u00faen tanto en fiestas y festivales, como en establecimientos privados en el municipio de Sant Josep de sa Talaia\",\"publisher\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#organization\",\"name\":\"Sant Josep \u00e9s m\u00fasica\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-SJEM.png\",\"contentUrl\":\"https:\\\/\\\/musica.santjosep.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-SJEM.png\",\"width\":213,\"height\":103,\"caption\":\"Sant Josep \u00e9s m\u00fasica\"},\"image\":{\"@id\":\"https:\\\/\\\/musica.santjosep.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sant-Josep-s-Msica-105337042007790\",\"https:\\\/\\\/x.com\\\/MusicaSantJosep\",\"https:\\\/\\\/www.instagram.com\\\/musicasantjosep\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBSLSUpqfrfsiOMVslmZEJA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oscuro baile de sal\u00f3n - Sant Josep \u00e9s m\u00fasica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musica.santjosep.org\/es\/discos\/oscuro-baile-de-salon\/","og_locale":"es_ES","og_type":"article","og_title":"Oscuro baile de sal\u00f3n - Sant Josep \u00e9s m\u00fasica","og_description":"Segundo \u00e1lbum del grupo de rock ibicenco Billy Flamingos, publicado en 2023. Incluye doce temas propios, producidos por Omar Gisbert.","og_url":"https:\/\/musica.santjosep.org\/es\/discos\/oscuro-baile-de-salon\/","og_site_name":"Sant Josep \u00e9s m\u00fasica","article_publisher":"https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790","article_modified_time":"2023-03-03T09:50:26+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/03\/Portada-Oscuro-baile-de-salon-1-1024x1024-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MusicaSantJosep","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musica.santjosep.org\/es\/discos\/oscuro-baile-de-salon\/","url":"https:\/\/musica.santjosep.org\/es\/discos\/oscuro-baile-de-salon\/","name":"Oscuro baile de sal\u00f3n - Sant Josep \u00e9s m\u00fasica","isPartOf":{"@id":"https:\/\/musica.santjosep.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musica.santjosep.org\/es\/discos\/oscuro-baile-de-salon\/#primaryimage"},"image":{"@id":"https:\/\/musica.santjosep.org\/es\/discos\/oscuro-baile-de-salon\/#primaryimage"},"thumbnailUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/03\/Portada-Oscuro-baile-de-salon-1-1024x1024-1.jpeg","datePublished":"2023-03-03T09:29:07+00:00","dateModified":"2023-03-03T09:50:26+00:00","breadcrumb":{"@id":"https:\/\/musica.santjosep.org\/es\/discos\/oscuro-baile-de-salon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musica.santjosep.org\/es\/discos\/oscuro-baile-de-salon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musica.santjosep.org\/es\/discos\/oscuro-baile-de-salon\/#primaryimage","url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/03\/Portada-Oscuro-baile-de-salon-1-1024x1024-1.jpeg","contentUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2023\/03\/Portada-Oscuro-baile-de-salon-1-1024x1024-1.jpeg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/musica.santjosep.org\/es\/discos\/oscuro-baile-de-salon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musica.santjosep.org\/es\/"},{"@type":"ListItem","position":2,"name":"Discos","item":"https:\/\/musica.santjosep.org\/es\/discos\/"},{"@type":"ListItem","position":3,"name":"Oscuro baile de sal\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/musica.santjosep.org\/es\/#website","url":"https:\/\/musica.santjosep.org\/es\/","name":"Sant Josep \u00e9s m\u00fasica","description":"Informaci\u00f3n actualizada de todos los conciertos, grupos y artistas que act\u00faen tanto en fiestas y festivales, como en establecimientos privados en el municipio de Sant Josep de sa Talaia","publisher":{"@id":"https:\/\/musica.santjosep.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musica.santjosep.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/musica.santjosep.org\/es\/#organization","name":"Sant Josep \u00e9s m\u00fasica","url":"https:\/\/musica.santjosep.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/musica.santjosep.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2022\/01\/logo-SJEM.png","contentUrl":"https:\/\/musica.santjosep.org\/wp-content\/uploads\/2022\/01\/logo-SJEM.png","width":213,"height":103,"caption":"Sant Josep \u00e9s m\u00fasica"},"image":{"@id":"https:\/\/musica.santjosep.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Sant-Josep-s-Msica-105337042007790","https:\/\/x.com\/MusicaSantJosep","https:\/\/www.instagram.com\/musicasantjosep\/","https:\/\/www.youtube.com\/channel\/UCBSLSUpqfrfsiOMVslmZEJA"]}]}},"_links":{"self":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/discos\/19135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/discos"}],"about":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/types\/discos"}],"author":[{"embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/discos\/19135\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/media\/19132"}],"wp:attachment":[{"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/media?parent=19135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/musica.santjosep.org\/es\/wp-json\/wp\/v2\/categories?post=19135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}